{"id":539,"count":3,"description":"","link":"https:\/\/aga.es\/en\/categoria-producto\/general-industry\/cylinders-and-locks\/special-cylinders\/sidese-model\/","name":"SIDESE model","slug":"sidese-model","taxonomy":"product_cat","parent":531,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SIDESE model Archives | AGA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aga.es\/en\/categoria-producto\/general-industry\/cylinders-and-locks\/special-cylinders\/sidese-model\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SIDESE model Archives | AGA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aga.es\/en\/categoria-producto\/general-industry\/cylinders-and-locks\/special-cylinders\/sidese-model\/\" \/>\n<meta property=\"og:site_name\" content=\"AGA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/aga.es\\\/en\\\/categoria-producto\\\/general-industry\\\/cylinders-and-locks\\\/special-cylinders\\\/sidese-model\\\/\",\"url\":\"https:\\\/\\\/aga.es\\\/en\\\/categoria-producto\\\/general-industry\\\/cylinders-and-locks\\\/special-cylinders\\\/sidese-model\\\/\",\"name\":\"SIDESE model Archives | AGA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aga.es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aga.es\\\/en\\\/categoria-producto\\\/general-industry\\\/cylinders-and-locks\\\/special-cylinders\\\/sidese-model\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aga.es\\\/en\\\/categoria-producto\\\/general-industry\\\/cylinders-and-locks\\\/special-cylinders\\\/sidese-model\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aga.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"General Industry\",\"item\":\"https:\\\/\\\/aga.es\\\/en\\\/categoria-producto\\\/general-industry\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cylinders and locks\",\"item\":\"https:\\\/\\\/aga.es\\\/en\\\/categoria-producto\\\/general-industry\\\/cylinders-and-locks\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Special cylinders\",\"item\":\"https:\\\/\\\/aga.es\\\/en\\\/categoria-producto\\\/special-cylinders\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"SIDESE model\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aga.es\\\/#website\",\"url\":\"https:\\\/\\\/aga.es\\\/\",\"name\":\"AGA\",\"description\":\"La industria de la cerrajer\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aga.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SIDESE model Archives | AGA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aga.es\/en\/categoria-producto\/general-industry\/cylinders-and-locks\/special-cylinders\/sidese-model\/","og_locale":"en_US","og_type":"article","og_title":"SIDESE model Archives | AGA","og_url":"https:\/\/aga.es\/en\/categoria-producto\/general-industry\/cylinders-and-locks\/special-cylinders\/sidese-model\/","og_site_name":"AGA","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aga.es\/en\/categoria-producto\/general-industry\/cylinders-and-locks\/special-cylinders\/sidese-model\/","url":"https:\/\/aga.es\/en\/categoria-producto\/general-industry\/cylinders-and-locks\/special-cylinders\/sidese-model\/","name":"SIDESE model Archives | AGA","isPartOf":{"@id":"https:\/\/aga.es\/#website"},"breadcrumb":{"@id":"https:\/\/aga.es\/en\/categoria-producto\/general-industry\/cylinders-and-locks\/special-cylinders\/sidese-model\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/aga.es\/en\/categoria-producto\/general-industry\/cylinders-and-locks\/special-cylinders\/sidese-model\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aga.es\/en\/"},{"@type":"ListItem","position":2,"name":"General Industry","item":"https:\/\/aga.es\/en\/categoria-producto\/general-industry\/"},{"@type":"ListItem","position":3,"name":"Cylinders and locks","item":"https:\/\/aga.es\/en\/categoria-producto\/general-industry\/cylinders-and-locks\/"},{"@type":"ListItem","position":4,"name":"Special cylinders","item":"https:\/\/aga.es\/en\/categoria-producto\/special-cylinders\/"},{"@type":"ListItem","position":5,"name":"SIDESE model"}]},{"@type":"WebSite","@id":"https:\/\/aga.es\/#website","url":"https:\/\/aga.es\/","name":"AGA","description":"La industria de la cerrajer\u00eda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aga.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/aga.es\/en\/wp-json\/wp\/v2\/product_cat\/539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aga.es\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/aga.es\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/aga.es\/en\/wp-json\/wp\/v2\/product_cat\/531"}],"wp:post_type":[{"href":"https:\/\/aga.es\/en\/wp-json\/wp\/v2\/product?product_cat=539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}